{"id":39,"count":23,"description":"","link":"https:\/\/www2.davarkg.com\/jp\/category\/branches\/%e7%a6%8f%e5%b2%a1%e7%a4%bc%e6%8b%9d%e6%89%80\/","name":"\u798f\u5ca1\u793c\u62dd\u6240","slug":"%e7%a6%8f%e5%b2%a1%e7%a4%bc%e6%8b%9d%e6%89%80","taxonomy":"category","parent":7,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u798f\u5ca1\u793c\u62dd\u6240 Archives - \u30ed\u30b5\u30f3\u30bc\u30eb\u30b9 \u30d1\u30b5\u30c7\u30ca\u306e\u65e5\u672c\u4eba\u6559\u4f1a \u30c0\u30f4\u30a1\u30fc\u30eb\u6559\u4f1a \u795e\u306e\u56fd<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www2.davarkg.com\/jp\/category\/branches\/\u798f\u5ca1\u793c\u62dd\u6240\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u798f\u5ca1\u793c\u62dd\u6240 Archives - \u30ed\u30b5\u30f3\u30bc\u30eb\u30b9 \u30d1\u30b5\u30c7\u30ca\u306e\u65e5\u672c\u4eba\u6559\u4f1a \u30c0\u30f4\u30a1\u30fc\u30eb\u6559\u4f1a \u795e\u306e\u56fd\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www2.davarkg.com\/jp\/category\/branches\/\u798f\u5ca1\u793c\u62dd\u6240\/\" \/>\n<meta property=\"og:site_name\" content=\"\u30ed\u30b5\u30f3\u30bc\u30eb\u30b9 \u30d1\u30b5\u30c7\u30ca\u306e\u65e5\u672c\u4eba\u6559\u4f1a \u30c0\u30f4\u30a1\u30fc\u30eb\u6559\u4f1a \u795e\u306e\u56fd\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www2.davarkg.com\\\/jp\\\/category\\\/branches\\\/%e7%a6%8f%e5%b2%a1%e7%a4%bc%e6%8b%9d%e6%89%80\\\/\",\"url\":\"https:\\\/\\\/www2.davarkg.com\\\/jp\\\/category\\\/branches\\\/%e7%a6%8f%e5%b2%a1%e7%a4%bc%e6%8b%9d%e6%89%80\\\/\",\"name\":\"\u798f\u5ca1\u793c\u62dd\u6240 Archives - \u30ed\u30b5\u30f3\u30bc\u30eb\u30b9 \u30d1\u30b5\u30c7\u30ca\u306e\u65e5\u672c\u4eba\u6559\u4f1a \u30c0\u30f4\u30a1\u30fc\u30eb\u6559\u4f1a \u795e\u306e\u56fd\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www2.davarkg.com\\\/jp\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www2.davarkg.com\\\/jp\\\/category\\\/branches\\\/%e7%a6%8f%e5%b2%a1%e7%a4%bc%e6%8b%9d%e6%89%80\\\/#breadcrumb\"},\"inLanguage\":\"ja\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www2.davarkg.com\\\/jp\\\/category\\\/branches\\\/%e7%a6%8f%e5%b2%a1%e7%a4%bc%e6%8b%9d%e6%89%80\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www2.davarkg.com\\\/jp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u652f\u90e8\u306e\u6d3b\u52d5\",\"item\":\"https:\\\/\\\/www2.davarkg.com\\\/jp\\\/category\\\/branches\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u798f\u5ca1\u793c\u62dd\u6240\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www2.davarkg.com\\\/jp\\\/#website\",\"url\":\"https:\\\/\\\/www2.davarkg.com\\\/jp\\\/\",\"name\":\"\u30ed\u30b5\u30f3\u30bc\u30eb\u30b9 \u30d1\u30b5\u30c7\u30ca\u306e\u65e5\u672c\u4eba\u6559\u4f1a \u30c0\u30f4\u30a1\u30fc\u30eb\u6559\u4f1a \u795e\u306e\u56fd\",\"description\":\"\u30ed\u30b5\u30f3\u30bc\u30eb\u30b9\u306e\u65e5\u672c\u4eba\u6559\u4f1a\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www2.davarkg.com\\\/jp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u798f\u5ca1\u793c\u62dd\u6240 Archives - \u30ed\u30b5\u30f3\u30bc\u30eb\u30b9 \u30d1\u30b5\u30c7\u30ca\u306e\u65e5\u672c\u4eba\u6559\u4f1a \u30c0\u30f4\u30a1\u30fc\u30eb\u6559\u4f1a \u795e\u306e\u56fd","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www2.davarkg.com\/jp\/category\/branches\/\u798f\u5ca1\u793c\u62dd\u6240\/","og_locale":"ja_JP","og_type":"article","og_title":"\u798f\u5ca1\u793c\u62dd\u6240 Archives - \u30ed\u30b5\u30f3\u30bc\u30eb\u30b9 \u30d1\u30b5\u30c7\u30ca\u306e\u65e5\u672c\u4eba\u6559\u4f1a \u30c0\u30f4\u30a1\u30fc\u30eb\u6559\u4f1a \u795e\u306e\u56fd","og_url":"https:\/\/www2.davarkg.com\/jp\/category\/branches\/\u798f\u5ca1\u793c\u62dd\u6240\/","og_site_name":"\u30ed\u30b5\u30f3\u30bc\u30eb\u30b9 \u30d1\u30b5\u30c7\u30ca\u306e\u65e5\u672c\u4eba\u6559\u4f1a \u30c0\u30f4\u30a1\u30fc\u30eb\u6559\u4f1a \u795e\u306e\u56fd","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www2.davarkg.com\/jp\/category\/branches\/%e7%a6%8f%e5%b2%a1%e7%a4%bc%e6%8b%9d%e6%89%80\/","url":"https:\/\/www2.davarkg.com\/jp\/category\/branches\/%e7%a6%8f%e5%b2%a1%e7%a4%bc%e6%8b%9d%e6%89%80\/","name":"\u798f\u5ca1\u793c\u62dd\u6240 Archives - \u30ed\u30b5\u30f3\u30bc\u30eb\u30b9 \u30d1\u30b5\u30c7\u30ca\u306e\u65e5\u672c\u4eba\u6559\u4f1a \u30c0\u30f4\u30a1\u30fc\u30eb\u6559\u4f1a \u795e\u306e\u56fd","isPartOf":{"@id":"https:\/\/www2.davarkg.com\/jp\/#website"},"breadcrumb":{"@id":"https:\/\/www2.davarkg.com\/jp\/category\/branches\/%e7%a6%8f%e5%b2%a1%e7%a4%bc%e6%8b%9d%e6%89%80\/#breadcrumb"},"inLanguage":"ja"},{"@type":"BreadcrumbList","@id":"https:\/\/www2.davarkg.com\/jp\/category\/branches\/%e7%a6%8f%e5%b2%a1%e7%a4%bc%e6%8b%9d%e6%89%80\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www2.davarkg.com\/jp\/"},{"@type":"ListItem","position":2,"name":"\u652f\u90e8\u306e\u6d3b\u52d5","item":"https:\/\/www2.davarkg.com\/jp\/category\/branches\/"},{"@type":"ListItem","position":3,"name":"\u798f\u5ca1\u793c\u62dd\u6240"}]},{"@type":"WebSite","@id":"https:\/\/www2.davarkg.com\/jp\/#website","url":"https:\/\/www2.davarkg.com\/jp\/","name":"\u30ed\u30b5\u30f3\u30bc\u30eb\u30b9 \u30d1\u30b5\u30c7\u30ca\u306e\u65e5\u672c\u4eba\u6559\u4f1a \u30c0\u30f4\u30a1\u30fc\u30eb\u6559\u4f1a \u795e\u306e\u56fd","description":"\u30ed\u30b5\u30f3\u30bc\u30eb\u30b9\u306e\u65e5\u672c\u4eba\u6559\u4f1a","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www2.davarkg.com\/jp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"}]}},"_links":{"self":[{"href":"https:\/\/www2.davarkg.com\/jp\/wp-json\/wp\/v2\/categories\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.davarkg.com\/jp\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www2.davarkg.com\/jp\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www2.davarkg.com\/jp\/wp-json\/wp\/v2\/categories\/7"}],"wp:post_type":[{"href":"https:\/\/www2.davarkg.com\/jp\/wp-json\/wp\/v2\/posts?categories=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}